{"id":1084,"date":"2019-04-30T13:23:13","date_gmt":"2019-04-30T13:23:13","guid":{"rendered":"https:\/\/bomain.nl\/?post_type=store&#038;p=1084"},"modified":"2019-04-30T13:23:14","modified_gmt":"2019-04-30T13:23:14","slug":"europa-boutique-1","status":"publish","type":"store","link":"https:\/\/bomain.nl\/en\/store\/europa-boutique-1\/","title":{"rendered":"Europa Boutique 1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mas Catherine Chemin Des<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">66700 Arleles S\/MER France<\/p>\n","protected":false},"template":"","class_list":["post-1084","store","type-store","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bomain.nl\/en\/wp-json\/wp\/v2\/store\/1084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bomain.nl\/en\/wp-json\/wp\/v2\/store"}],"about":[{"href":"https:\/\/bomain.nl\/en\/wp-json\/wp\/v2\/types\/store"}],"wp:attachment":[{"href":"https:\/\/bomain.nl\/en\/wp-json\/wp\/v2\/media?parent=1084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}